{"id":41251,"date":"2025-06-20T11:26:52","date_gmt":"2025-06-20T03:26:52","guid":{"rendered":"https:\/\/zetarmold.com\/?p=41251"},"modified":"2026-04-09T08:10:29","modified_gmt":"2026-04-09T00:10:29","slug":"nozioni-di-base-del-glossario-dello-stampaggio-a-iniezione","status":"publish","type":"post","link":"https:\/\/zetarmold.com\/it\/nozioni-di-base-del-glossario-dello-stampaggio-a-iniezione\/","title":{"rendered":"Glossario e nozioni di base dello stampaggio a iniezione"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: &lt;a href=\"https:>Stampo a iniezione<\/a>Glossario e basi dell\u2019ingegneria\u201d style=\u201dborder-radius: 12px\u201d width=\u201d100%\u201d height=\u201d152\u2033 frameborder=\u201d0\u2033 allowfullscreen allow=\u201dautoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\u201d loading=\u201dlazy\u201d src=\u201dhttps:\/\/open.spotify.com\/embed\/episode\/1CMeeNSCg0rGXCvSnkrUWu?si=UHbn-LZ1RfeqbnUJMJ2REg&amp;utm_source=oembed\u201d&gt;<\/iframe>\n<\/div>\n<\/figure>\n<p><strong>Introduction: plastic injection molding is a process where plastic particles are heated until they melt and then injected into a mold cavity at high pressure and speed to make a product with the right structure, look, and size.<\/strong><\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-902 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"386\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11.jpg\" alt=\"\" class=\"wp-image-41263\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11-300x193.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Quando si effettua lo stampaggio, bisogna pensare a molte cose per assicurarsi che il prodotto sia buono (come l'aspetto, le dimensioni, la resistenza e altre cose del genere) e che sia veloce (come il tempo necessario per produrlo). Questo articolo parler\u00e0 delle parole e delle cose da sapere per lo stampaggio a iniezione.<\/strong><\/p>\n<h2 class=\"wp-block-heading\">Parametri di stampaggio a iniezione<\/h2>\n<p><strong>Definizione: <\/strong>La qualit\u00e0 dello stampaggio del prodotto \u00e8 influenzata da cinque fattori: temperatura, velocit\u00e0, pressione, posizione e tempo. Le impostazioni di questi cinque fattori sono i parametri di stampaggio.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-903 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"397\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c.jpg\" alt=\"\" class=\"wp-image-41261\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c-300x199.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Temperatura <\/h3>\n<h4 class=\"wp-block-heading\">Temperatura di asciugatura<\/h4>\n<p><strong>Definizione: <\/strong>La temperatura necessaria per asciugare la plastica prima di poterla trasformare in qualcosa di buono.<\/p>\n<p><strong>Funzione:<\/strong> Assicurarsi che la plastica sia il pi\u00f9 possibile asciutta, ma non troppo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-904 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1.jpg\" alt=\"\" class=\"wp-image-41264\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Non bruciarlo o farlo attaccare (sciogliere), farlo il pi\u00f9 velocemente possibile, farlo il pi\u00f9 freddo possibile senza che non funzioni, cose diverse richiedono tempi e temperature diverse, usare ci\u00f2 che dicono le persone che lo hanno prodotto.<\/p>\n<h4 class=\"wp-block-heading\">Temperatura del materiale<\/h4>\n<p><strong>Definizione:<\/strong> La temperatura impostata sul tubo del materiale assicura che lo stampaggio avvenga senza problemi.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-905 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0.jpg\" alt=\"\" class=\"wp-image-41266\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong> Riscaldare la camera del materiale della formatrice con l'anello di riscaldamento elettrico per far passare la materia prima da granulare a fusa, assicurarsi che il polimero sia ben fuso (colla fusa), assicurarsi che lo stampo venga riempito e che lo stampaggio avvenga senza problemi.<\/p>\n<p><strong>Principio:<\/strong> Per non far decomporre e carbonizzare la plastica, salire dalla sezione di alimentazione all'ugello; la temperatura dell'ugello deve essere leggermente inferiore a quella della sezione anteriore della canna per evitare la formazione di bava, e la temperatura necessaria dipende dal materiale utilizzato.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-906 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"452\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1.jpg\" alt=\"\" class=\"wp-image-41267\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Temperatura dello stampo<\/h4>\n<p><strong>Definizione: <\/strong>La temperatura della superficie dello stampo su cui il prodotto viene a contatto<\/p>\n<p><strong>Funzione:<\/strong> Controllare la velocit\u00e0 di raffreddamento del prodotto nello stampo e l'aspetto del prodotto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-907 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3.jpeg\" alt=\"\" class=\"wp-image-41073\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3-300x200.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Pensate al tipo di plastica che utilizzate, alle dimensioni e alla forma del prodotto e a come viene realizzato lo stampo. Pensate anche a come la plastica entra nello stampo.<\/p>\n<h3 class=\"wp-block-heading\">Velocit\u00e0<\/h3>\n<h4 class=\"wp-block-heading\">Velocit\u00e0 di iniezione<\/h4>\n<p><strong>Definizione:<\/strong> La velocit\u00e0 con cui la plastica fusa viene iniettata dall'ugello nella cavit\u00e0 dello stampo a una determinata pressione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-908 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12.jpeg\" alt=\"\" class=\"wp-image-41254\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12-300x169.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong> Aumentando la velocit\u00e0 di iniezione si aumenta la pressione di riempimento. Aumentando la velocit\u00e0 di iniezione si pu\u00f2 aumentare la lunghezza del flusso. Ci\u00f2 rende uniforme la qualit\u00e0 del prodotto. L'alta viscosit\u00e0 e la velocit\u00e0 di flusso ad alta velocit\u00e0 di iniezione sono adatte per i prodotti a lunga lavorazione. Flusso uniforme a bassa velocit\u00e0 e dimensioni stabili del prodotto.<\/p>\n<p><strong>Principio:<\/strong> Per evitare il supporto dello stampo e l'overflow, per evitare bruciature dovute all'eccessiva velocit\u00e0 e per garantire la qualit\u00e0 del prodotto, si consiglia di scegliere il riempimento ad alta velocit\u00e0 per abbreviare il ciclo di stampaggio.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-909 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17.jpeg\" alt=\"\" class=\"wp-image-41255\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17-300x156.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Velocit\u00e0 di fusione<\/h4>\n<p><strong>Definizione: <\/strong>La velocit\u00e0 della vite quando fonde la plastica.<\/p>\n<p><strong>Funzione:<\/strong> Un parametro molto importante che influisce sulla capacit\u00e0 di plastificazione, sulla qualit\u00e0 della plastificazione e sul ciclo di stampaggio. Maggiore \u00e8 la velocit\u00e0, pi\u00f9 alta \u00e8 la temperatura di fusione e pi\u00f9 forte \u00e8 la capacit\u00e0 di plastificazione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-910 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7.jpeg\" alt=\"\" class=\"wp-image-41256\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7-300x150.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Quando si aumenta la velocit\u00e0 della vite, la qualit\u00e0 della plastificazione diminuisce.<\/p>\n<h4 class=\"wp-block-heading\">Velocit\u00e0 di ritrazione<\/h4>\n<p><strong>Definizione: <\/strong>Una volta posizionata, la vite (dosatrice) si ritrae per una certa distanza a una certa velocit\u00e0. La velocit\u00e0 di arretramento \u00e8 la velocit\u00e0 di ritrazione.<\/p>\n<p><strong>Funzione:<\/strong> Riducono il volume specifico della colata, riducono la pressione nella cavit\u00e0 della colata e ne impediscono la fuoriuscita.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-911 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1.jpg\" alt=\"\" class=\"wp-image-41268\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>La regolazione deve essere adattata alla velocit\u00e0 della vite e alla contropressione.<\/p>\n<h4 class=\"wp-block-heading\">Velocit\u00e0 di apertura e chiusura dello stampo<\/h4>\n<p><strong>Definizione: <\/strong>La velocit\u00e0 di apertura e chiusura dello stampo.<\/p>\n<p><strong>Funzione:<\/strong> Una velocit\u00e0 ragionevole di apertura e chiusura dello stampo \u00e8 indispensabile per garantire il funzionamento regolare della macchina e della produzione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-912 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"373\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21.jpg\" alt=\"\" class=\"wp-image-41257\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21-300x187.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Affinch\u00e9 la macchina funzioni in modo fluido e con minori vibrazioni, la velocit\u00e0 di apertura e chiusura dello stampo deve essere impostata in modo da rendere il tempo di apertura e chiusura dello stampo il pi\u00f9 breve possibile e la commutazione della velocit\u00e0 di apertura e chiusura dello stampo deve essere ragionevole, seguendo il principio di lento-veloce-lento.<\/p>\n<h4 class=\"wp-block-heading\">Velocit\u00e0 dell'espulsore in avanti e indietro<\/h4>\n<p><strong>Definizione:<\/strong> La velocit\u00e0 con cui il perno di espulsione si sposta in avanti e si ritrae dopo l'apertura dello stampo.<\/p>\n<p><strong>Funzione:<\/strong> Per assicurarsi che il pezzo esca dallo stampo senza piegarsi, deformarsi o incrinarsi.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-913 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"309\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2.jpeg\" alt=\"\" class=\"wp-image-41258\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2-300x155.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>L'estremit\u00e0 anteriore deve muoversi lentamente per evitare di piegare o rompere il pezzo, mentre l'estremit\u00e0 posteriore deve muoversi velocemente, ma in modo fluido.<\/p>\n<h3 class=\"wp-block-heading\">Pressione <\/h3>\n<h4 class=\"wp-block-heading\">Un colpo di pressione<\/h4>\n<p><strong>Definizione: <\/strong>La vite spinge la materia prima dalla tramoggia allo stampo.&nbsp;<\/p>\n<p><strong>Funzione: <\/strong>Per assicurarsi che lo stampo sia riempito e che il pezzo esca correttamente.&nbsp;<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-914 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1.jpg\" alt=\"\" class=\"wp-image-41269\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Deve rientrare nel limite di pressione della macchina, la curva di iniezione deve rientrare nel range e la linea di pressione deve essere liscia e costante, in modo da non avere flash o colpi corti.<\/p>\n<h4 class=\"wp-block-heading\">Pressione di iniezione secondaria (pressione di mantenimento)<\/h4>\n<p><strong>Definizione:<\/strong> Dal momento in cui la cavit\u00e0 dello stampo viene riempita di plastica fino al completo raffreddamento e alla chiusura della porta, \u00e8 necessaria una pressione relativamente elevata per mantenere il tempo. Questa pressione \u00e8 chiamata pressione di mantenimento.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-915 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2.jpg\" alt=\"\" class=\"wp-image-41270\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong> Aggiungere altro materiale vicino alla posizione del gate e impedire che la plastica non indurita nella cavit\u00e0 dello stampo rifluisca sotto la pressione rimanente prima che il gate si raffreddi e si chiuda.<\/p>\n<p>In questo modo si evita il ritiro dei pezzi, si eliminano i segni di affossamento, si riducono le trappole d'aria e si evita che i pezzi si attacchino allo stampo, si pieghino o si rompano a causa dell'eccessiva pressione di iniezione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-916 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0.jpg\" alt=\"\" class=\"wp-image-41271\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> La pressione e la velocit\u00e0 di mantenimento sono solitamente impostate a 50~60% della pressione e della velocit\u00e0 massime quando la plastica riempie la cavit\u00e0 dello stampo. La durata del tempo di mantenimento \u00e8 legata alla temperatura del materiale.<\/p>\n<p>Il cancello ad alta temperatura ha un tempo di chiusura pi\u00f9 lungo e un tempo di mantenimento pi\u00f9 lungo. La pressione di mantenimento \u00e8 legata all'area proiettata e allo spessore della parete del prodotto. I prodotti spessi e grandi richiedono un tempo maggiore. La pressione di mantenimento \u00e8 legata alle dimensioni, alla forma e alla grandezza del cancello.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-917 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2.jpg\" alt=\"\" class=\"wp-image-41272\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Pressione della resina (contropressione)<\/h4>\n<p><strong>Definizione:<\/strong> La pressione che si crea nella cavit\u00e0 di fusione durante il processo di plastificazione della plastica.<\/p>\n<p><strong>Funzione:<\/strong> Per aumentare il peso specifico della colata, garantire una plastificazione uniforme della colata, ridurre il contenuto di gas nella colata e migliorare la qualit\u00e0 della plastificazione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-918 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1.jpg\" alt=\"\" class=\"wp-image-41273\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Quando si regola la pressione della resina, \u00e8 necessario tenere conto delle propriet\u00e0 del materiale plastico. Occorre inoltre considerare l'aspetto e le dimensioni del prodotto.<\/p>\n<h4 class=\"wp-block-heading\">Pressione di serraggio<\/h4>\n<p><strong>Definizione: <\/strong>Il sistema di bloccaggio chiude lo stampo per evitare che si apra durante l'iniezione e il confezionamento della plastica.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-919 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1.jpg\" alt=\"\" class=\"wp-image-41274\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione: <\/strong>Per evitare che lo stampo si apra durante l'iniezione e il confezionamento della plastica, per dare al pezzo un bell'aspetto e per ottenere il pezzo della giusta dimensione.<\/p>\n<p><strong>Principio:<\/strong> Il tonnellaggio della pinza dipende dalle dimensioni del pezzo e dalla dimensione della macchina.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-920 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2.jpg\" alt=\"\" class=\"wp-image-41275\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>In generale, quanto pi\u00f9 piccolo \u00e8 il tonnellaggio della pinza, tanto meglio \u00e8. Il tonnellaggio della pinza non deve essere superiore alla pressione nominale della macchina, ma deve essere sufficientemente alto per evitare che il pezzo abbia un flash.<\/p>\n<h4 class=\"wp-block-heading\">Pressione di protezione dalla muffa<\/h4>\n<p><strong>Definizione:&nbsp;<\/strong>Quando si realizzano gli stampi, di solito si passa dall'alta pressione e dall'alta velocit\u00e0 alla bassa pressione e alla bassa velocit\u00e0 prima di utilizzare l'alta pressione per bloccare lo stampo. La bassa pressione prima del bloccaggio ad alta pressione \u00e8 chiamata pressione di protezione dello stampo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-921 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3.jpg\" alt=\"\" class=\"wp-image-41277\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:&nbsp;<\/strong>Per evitare che lo stampo venga schiacciato da oggetti estranei presenti nello stampo quando si utilizzano alta pressione e alta velocit\u00e0.<\/p>\n<p><strong>Principio:<\/strong> Prima di procedere all'impostazione e al debug, \u00e8 necessario regolare lo spessore dello stampo; il valore di impostazione iniziale deve essere il pi\u00f9 basso possibile e non deve superare i 20% della forza di serraggio. Quando non \u00e8 possibile correggere lo stampo, il valore di impostazione deve essere aumentato lentamente.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-922 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1.jpg\" alt=\"\" class=\"wp-image-41278\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Posizione <\/h3>\n<h4 class=\"wp-block-heading\">Posizione di apertura dello stampo<\/h4>\n<p><strong>Definizione:<\/strong> La posizione dello stampo maschio rispetto alla superficie dello stampo femmina dopo la separazione degli stampi maschio e femmina.<\/p>\n<p><strong>Funzione:<\/strong>&nbsp;Assicuratevi di poter rimuovere facilmente l'oggetto dallo stampo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-923 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"421\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344.jpg\" alt=\"\" class=\"wp-image-40625\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344-300x211.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Andare il pi\u00f9 velocemente possibile per tutto il tempo possibile. La posizione di massima apertura dello stampo deve basarsi sul principio della facilit\u00e0 di rimozione (anche da parte del robot) e di non danneggiare la superficie dello stampo femmina durante l'estrazione. La posizione massima di apertura dello stampo deve essere basata sul ciclo di stampaggio pi\u00f9 breve.<\/p>\n<h4 class=\"wp-block-heading\">Corsa di espulsione e ritrazione<\/h4>\n<p><strong>Definizione:<\/strong> La posizione estrema dell'espulsore che viene espulso e ritratto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-924 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1.jpg\" alt=\"\" class=\"wp-image-41279\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong> La corsa dell'espulsore serve a limitare il movimento in avanti e all'indietro dell'espulsore per garantire una sformatura fluida del prodotto e un reset accurato dell'espulsore. Per alcuni stampi a molla, la corsa dell'espulsore serve anche come protezione del limite di espulsione.<\/p>\n<p><strong>Principio: <\/strong>La distanza di espulsione deve seguire il principio \"da piccolo a grande\" e lo stampaggio deve essere fluido. Per gli stampi a molla senza perni di espulsione, \u00e8 necessario assicurarsi che la molla non venga schiacciata durante l'espulsione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-925 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0.jpg\" alt=\"\" class=\"wp-image-41280\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Il perno di espulsione non deve trovarsi pi\u00f9 in alto della superficie dello stampo maschio quando \u00e8 retratto. Il perno di espulsione dello stampo con cursore deve essere retratto per evitare interferenze reciproche.<\/p>\n<h4 class=\"wp-block-heading\">Corsa di misurazione<\/h4>\n<p><strong>Definizione:<\/strong> Dopo l'inizio della plastificazione, la coclea inizia a retrocedere dalla posizione di fine iniezione sotto la forza della massa plastica fusa, fino a raggiungere il finecorsa per l'arretramento durante il processo di rotazione. Questo processo \u00e8 chiamato corsa di dosaggio.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-926 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3.jpg\" alt=\"\" class=\"wp-image-41281\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong>Assicuratevi di avere abbastanza plastica per riempire la cavit\u00e0 dello stampo, in modo da ottenere l'aspetto e le dimensioni desiderate per il vostro prodotto.<\/p>\n<p><strong>Principio : <\/strong>La corsa di dosaggio deve essere impostata in base alle dimensioni del prodotto e alle dimensioni della macchina. La corsa di dosaggio non deve essere troppo grande per evitare che l'iniezione di plastica in eccesso rimanga troppo a lungo nel tubo del materiale e provochi la carbonizzazione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-927 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0.jpg\" alt=\"\" class=\"wp-image-41282\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La corsa di dosaggio non pu\u00f2 essere troppo piccola per garantire un riempimento sufficiente ed evitare danni meccanici alla vite e all'ugello. Dovrebbe esserci un buffer di 3~5 mm.<\/p>\n<h4 class=\"wp-block-heading\">Corsa di iniezione<\/h4>\n<p><strong>Definizione:<\/strong> La vite si muove avanti e indietro durante il processo di iniezione.<\/p>\n<p><strong>Funzione: <\/strong>La vite si muove velocemente o lentamente per controllare il flusso della plastica.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-928 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3.jpg\" alt=\"\" class=\"wp-image-41283\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio : <\/strong>La posizione di dosaggio \u00e8 determinata dalla quantit\u00e0 di riempimento del prodotto finito. Di solito, a questo valore vengono aggiunti 3~5 mm di impulso per determinare l'impostazione finale. Il punto di commutazione alla seconda velocit\u00e0 viene solitamente commutato sul canale caldo e sulla posizione della testa.<\/p>\n<p>Il punto di commutazione alla terza velocit\u00e0 \u00e8 impostato con 90% del grado di riempimento del prodotto stampato. Il punto di commutazione del mantenimento della pressione \u00e8 generalmente impostato nella posizione 90% del grado di riempimento del prodotto finito.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-929 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3.jpg\" alt=\"\" class=\"wp-image-41284\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Importo della ritrattazione<\/h4>\n<p><strong>Definizione: <\/strong>Dopo che la vite \u00e8 stata preplastificata (dosata) in posizione, si ritira per una certa distanza in linea retta. Questa azione di arretramento \u00e8 chiamata allentamento all'indietro e la distanza di allentamento \u00e8 chiamata quantit\u00e0 di allentamento o quantit\u00e0 di antiritardo.<\/p>\n<p><strong>principio:<\/strong> Pu\u00f2 essere impostato in base alla viscosit\u00e0, alla densit\u00e0 relativa e alla situazione effettiva della materia prima plastica. Una quantit\u00e0 maggiore di rilascio causer\u00e0 la miscelazione della massa fusa con bolle, compromettendo la qualit\u00e0 del prodotto.<\/p>\n<p><strong>Funzione: <\/strong>La valvola di contropressione aumenta il volume della colata nella camera di dosaggio, abbassa la pressione interna e impedisce alla colata di uscire dalla camera di dosaggio.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-930 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3.jpg\" alt=\"\" class=\"wp-image-41285\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>L'impostazione della quantit\u00e0 di rilascio deve essere adattata alla velocit\u00e0 della vite e alla contropressione. Per le materie prime con viscosit\u00e0 pi\u00f9 elevata (come il PC), \u00e8 possibile impostare la quantit\u00e0 di rilascio.<\/p>\n<h4 class=\"wp-block-heading\">Posizione residua<\/h4>\n<p><strong>Definizione:<\/strong>&nbsp;Una volta terminata l'iniezione della vite, non si vuole spingere fuori tutto il materiale fuso nella testa della vite. Si vuole lasciarne un po'. Alla fine ne rimane un po', che \u00e8 il tampone.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-931 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2.jpg\" alt=\"\" class=\"wp-image-41286\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong>&nbsp;Prevenzione degli incidenti causati dalla testa della vite che colpisce l'ugello. Controllare la quantit\u00e0 di plastica iniettata ogni volta.<\/p>\n<p><strong>principio:<\/strong> Non fare il tampone troppo grande o troppo piccolo. Se \u00e8 troppo grande, si avr\u00e0 un avanzo di materiale eccessivo, che causer\u00e0 perdite di pressione e degrader\u00e0 la materia prima. Se \u00e8 troppo piccolo, non si otterr\u00e0 l'effetto tampone desiderato. La regola generale \u00e8 di creare un tampone da 3 a 5 mm.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-932 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2.jpg\" alt=\"\" class=\"wp-image-41287\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Tempo <\/h3>\n<h4 class=\"wp-block-heading\">Ciclo<\/h4>\n<p><strong>Definizione: <\/strong>Il tempo che intercorre tra la fine dell'apertura dello stampo e la fine dell'apertura dello stampo dopo l'iniezione successiva \u00e8 raffreddato.<\/p>\n<p><strong>Funzione:<\/strong> Assicurarsi che il prodotto sia formato e completamente raffreddato e fissato.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-933 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"496\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3.jpg\" alt=\"\" class=\"wp-image-41289\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3-300x248.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Accorciare il pi\u00f9 possibile il ciclo. L'accorciamento del ciclo deve avvenire con il presupposto di garantire la qualit\u00e0 del prodotto.<\/p>\n<h4 class=\"wp-block-heading\">Tempo di raffreddamento<\/h4>\n<p><strong>Definizione:<\/strong> Il tempo necessario affinch\u00e9 il prodotto si raffreddi e si indurisca senza rovinarsi dopo averlo tolto dallo stampo.<\/p>\n<p><strong>&nbsp;Funzione:<\/strong> Lasciare indurire il prodotto. Evitare che il prodotto si rovini.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-934 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3.jpg\" alt=\"\" class=\"wp-image-41290\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Il tempo di raffreddamento \u00e8 una parte importante del tempo di ciclo e deve essere il pi\u00f9 breve possibile, pur garantendo la qualit\u00e0 del prodotto. (2) Il tempo di raffreddamento dipende dalla temperatura della colata, dalla temperatura dello stampo, dalla forma e dallo spessore del prodotto.<\/p>\n<h4 class=\"wp-block-heading\">Tempo di mantenimento della pressione<\/h4>\n<p><strong>Definizione: <\/strong>La pressione che continua ad essere applicata dopo l'iniezione per evitare il riflusso di plastica dopo l'iniezione e la compensazione del ritiro per raffreddamento.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-935 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2.jpg\" alt=\"\" class=\"wp-image-41291\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funzione:<\/strong> Prevenzione del riflusso della massa fusa dopo l'iniezione. Compensazione del ritiro da raffreddamento.<\/p>\n<p><strong>principio:<\/strong> Il tempo di mantenimento della pressa dipende dallo spessore del prodotto. Il tempo di mantenimento varia a seconda della temperatura della massa fusa.<\/p>\n<p>Pi\u00f9 alta \u00e8 la temperatura, pi\u00f9 lungo \u00e8 il tempo richiesto, mentre pi\u00f9 bassa \u00e8 la temperatura, pi\u00f9 breve \u00e8 il tempo di mantenimento. Per migliorare l'efficienza della produzione, il tempo di mantenimento deve essere il pi\u00f9 breve possibile, pur garantendo la qualit\u00e0 del prodotto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-936 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1.jpg\" alt=\"\" class=\"wp-image-41292\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Tempo di iniezione<\/h4>\n<p><strong>Definizione: <\/strong>Il tempo necessario affinch\u00e9 la colata riempia l'intera cavit\u00e0.<\/p>\n<p><strong>Funzione:<\/strong> Il tempo di iniezione \u00e8 determinato da fattori quali la pressione di iniezione, la velocit\u00e0 di iniezione e le dimensioni del prodotto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-937 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1.jpg\" alt=\"\" class=\"wp-image-41293\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Il tempo di iniezione deve essere il pi\u00f9 breve possibile, pur garantendo lo stampaggio del prodotto. Il tempo di iniezione \u00e8 influenzato da fattori quali la temperatura del materiale e la temperatura dello stampo.<\/p>\n<h4 class=\"wp-block-heading\">Tempo di fusione<\/h4>\n<p><strong>Definizione:<\/strong> Il tempo necessario alla vite per raggiungere l'estremit\u00e0 della canna dopo l'interruzione dell'iniezione.<\/p>\n<p><strong>Funzione:<\/strong> Assicurarsi che la plastica fusa sia sufficiente.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-938 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1.jpg\" alt=\"\" class=\"wp-image-41294\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> La velocit\u00e0 della vite e la contropressione sono correlate. Non lasciare che la plastica fusa rimanga troppo a lungo nella vite, altrimenti si decompone e carbonizza ad alta temperatura per lungo tempo.<\/p>\n<h4 class=\"wp-block-heading\">Tempo di asciugatura<\/h4>\n<p><strong>Definizione:<\/strong> Il tempo necessario per l'essiccazione preventiva delle materie prime mediante apparecchiature di essiccazione.<\/p>\n<p><strong>Funzione:<\/strong> Rendere la superficie lucida, renderla flessibile e resistente, non lasciare che si crepi o faccia bolle all'interno. Renderlo facile da modellare e veloce da modellare. Fare in modo che le materie prime non siano bagnate o umide.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-939 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2.jpg\" alt=\"\" class=\"wp-image-41295\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Il tempo di essiccazione varia a seconda delle materie prime. Impostare correttamente il tempo di essiccazione. Un tempo troppo lungo riduce l'efficienza dell'essiccazione e pu\u00f2 causare l'agglomerazione delle materie prime. Se troppo breve, l'effetto di essiccazione sar\u00e0 scarso.<\/p>\n<h2 class=\"wp-block-heading\">Come regolare i parametri del processo di stampaggio a iniezione<\/h2>\n<h3 class=\"wp-block-heading\">Temperatura<\/h3>\n<p>Temperature measurement and control are super important in injection molding. It\u2019s pretty easy to make these measurements, but most injection molding machines don\u2019t have enough temperature sampling points or lines.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-940 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1.jpg\" alt=\"\" class=\"wp-image-41296\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La maggior parte delle macchine per lo stampaggio a iniezione utilizza termocoppie per rilevare la temperatura. Una termocoppia \u00e8 costituita da due fili diversi collegati a un'estremit\u00e0. Se un'estremit\u00e0 \u00e8 pi\u00f9 calda dell'altra, viene generato un piccolo segnale. Quanto pi\u00f9 caldo \u00e8, tanto pi\u00f9 forte \u00e8 il segnale.<\/p>\n<h4 class=\"wp-block-heading\">Temperatura di fusione<\/h4>\n<p>Le termocoppie sono anche ampiamente utilizzate come sensori nei sistemi di controllo della temperatura. Sullo strumento di controllo, si imposta la temperatura desiderata e il display del sensore confronta la temperatura rilevata con quella impostata.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-941 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3.jpg\" alt=\"\" class=\"wp-image-41297\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Nel sistema pi\u00f9 semplice, quando la temperatura raggiunge il punto stabilito, l'alimentazione si spegne e si riaccende quando la temperatura scende. Questo sistema \u00e8 chiamato controllo on-off perch\u00e9 \u00e8 acceso o spento.<\/p>\n<h4 class=\"wp-block-heading\">Controllo della temperatura<\/h4>\n<p>La temperatura di fusione \u00e8 importante e la temperatura del cilindro di iniezione utilizzata \u00e8 solo una guida. La temperatura della colata pu\u00f2 essere misurata all'ugello o con il metodo del getto d'aria.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-942 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0.jpg\" alt=\"\" class=\"wp-image-41298\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>L'impostazione della temperatura del cilindro di iniezione dipende dalla temperatura del materiale fuso, dalla velocit\u00e0 della vite, dalla contropressione, dalla dimensione dei pallini e dal ciclo di iniezione.<\/p>\n<p>Se non si conosce il tipo di plastica con cui si lavora, iniziare con l'impostazione pi\u00f9 bassa. Il cilindro dei pallini \u00e8 diviso in zone, ma non sono tutte impostate alla stessa temperatura.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-943 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0.jpg\" alt=\"\" class=\"wp-image-41299\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Se si esegue un lavoro lungo o ad alte temperature, impostare una temperatura pi\u00f9 bassa per la prima zona.<\/p>\n<p>In questo modo si evita che la plastica si sciolga e vada in cortocircuito troppo presto. Prima di iniziare lo stampaggio, accertarsi che l'olio idraulico, la tramoggia pi\u00f9 vicina, lo stampo e il cilindro di iniezione siano alla giusta temperatura.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-944 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1.jpg\" alt=\"\" class=\"wp-image-41300\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Pressione di iniezione<\/h3>\n<p>\u00c8 la pressione che fa muovere la plastica. \u00c8 possibile misurarla con un sensore sull'ugello o sulla linea idraulica.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-945 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0.jpg\" alt=\"\" class=\"wp-image-41301\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Non c'\u00e8 un numero fisso. Pi\u00f9 \u00e8 difficile riempire lo stampo, pi\u00f9 alta \u00e8 la pressione di iniezione. La pressione della linea di iniezione e la pressione di iniezione sono direttamente correlate.<\/p>\n<h4 class=\"wp-block-heading\">Pressione del primo stadio e pressione del secondo stadio<\/h4>\n<p>Durante la fase di riempimento del ciclo di iniezione, potrebbe essere necessaria un'elevata pressione di iniezione per mantenere la velocit\u00e0 di iniezione desiderata. Una volta che lo stampo \u00e8 pieno, non \u00e8 pi\u00f9 necessaria un'alta pressione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-946 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0.jpg\" alt=\"\" class=\"wp-image-41302\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Tuttavia, se si iniettano alcuni materiali termoplastici semicristallini (come PA e POM), la struttura si degrada se si cambia improvvisamente la pressione, quindi a volte non \u00e8 necessario usare la seconda pressione.<\/p>\n<h4 class=\"wp-block-heading\">Pressione di serraggio<\/h4>\n<p>Per contrastare la pressione di iniezione, \u00e8 necessario utilizzare la pressione di serraggio. Non limitatevi a selezionare automaticamente il valore massimo disponibile, ma considerate l'area proiettata e calcolate un valore adeguato.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-947 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0.jpg\" alt=\"\" class=\"wp-image-41303\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>L'area proiettata del pezzo stampato a iniezione \u00e8 l'area massima vista dalla direzione di applicazione della forza di chiusura.<\/p>\n<p>Per la maggior parte <a href=\"https:\/\/zetarmold.com\/it\/\" data-type=\"link\" data-id=\"https:\/\/zetarmold.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">stampaggio a iniezione<\/a> \u00e8 di circa 2 tonnellate per pollice quadrato, o 31 meganewton per metro quadrato. Ma questo \u00e8 solo un valore basso e deve essere usato come regola approssimativa, perch\u00e9, se il pezzo ha una certa profondit\u00e0, bisogna considerare la parete laterale.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-948 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1.jpg\" alt=\"\" class=\"wp-image-41304\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Contropressione<\/h4>\n<p>Questa \u00e8 la pressione che deve essere generata e superata prima che la vite si ritiri. Sebbene una contropressione elevata sia utile per la distribuzione uniforme dei coloranti e la fusione delle materie plastiche, essa rende pi\u00f9 lento il ritorno della vite centrale, riduce la lunghezza delle fibre contenute nella plastica di riempimento e aumenta lo stress della pressa a iniezione.<\/p>\n<p>Quindi, pi\u00f9 bassa \u00e8 la contropressione, meglio \u00e8.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-949 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1.jpg\" alt=\"\" class=\"wp-image-41305\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>In ogni caso, nessuno dei due pu\u00f2 superare la pressione di stampaggio della macchina ad iniezione.<\/p>\n<h4 class=\"wp-block-heading\">Pressione dell'ugello<\/h4>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-950 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0.jpg\" alt=\"\" class=\"wp-image-41306\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La pressione dell'ugello \u00e8 la pressione all'interno dell'ugello. \u00c8 all'incirca la pressione che fa fluire la plastica. Non ha un valore fisso, ma aumenta quando lo stampo diventa pi\u00f9 difficile da riempire. La pressione dell'ugello, la pressione della linea e la pressione di iniezione sono tutte correlate.<\/p>\n<p>La pressione dell'ugello \u00e8 inferiore di circa 10% rispetto alla pressione di iniezione. In una macchina per lo stampaggio a iniezione a vite, la perdita di pressione pu\u00f2 essere di circa 10%. In una macchina per lo stampaggio a iniezione a pistone, la perdita di pressione pu\u00f2 essere di 50%.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-951 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3.jpg\" alt=\"\" class=\"wp-image-41308\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Velocit\u00e0 di iniezione<\/h3>\n<p>Si tratta della velocit\u00e0 con cui lo stampo si riempie quando la vite viene utilizzata come uno stantuffo. Quando si realizzano pezzi a parete sottile, \u00e8 necessario sparare velocemente per riempire lo stampo prima che la plastica si congeli e crei una superficie pi\u00f9 liscia.<\/p>\n<p>Durante il riempimento utilizziamo una serie di velocit\u00e0 di sparo programmate per evitare difetti come spruzzi o aria intrappolata. L'iniezione pu\u00f2 essere effettuata con un sistema di controllo ad anello aperto o chiuso.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-952 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8.jpeg\" alt=\"\" class=\"wp-image-41309\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8-300x169.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Indipendentemente dalla velocit\u00e0 di iniezione, \u00e8 necessario registrare la velocit\u00e0 sul foglio di registrazione insieme al tempo. Il tempo \u00e8 il tempo necessario allo stampo per raggiungere la pressione di iniezione del primo stadio impostata, che fa parte del tempo di avanzamento della vite.<\/p>\n<h2 class=\"wp-block-heading\">Sintesi<\/h2>\n<p>La qualit\u00e0 e l'efficienza dello stampaggio a iniezione dipendono dall'impostazione ottimale di parametri quali temperatura, velocit\u00e0, pressione, posizione e tempo. La corretta regolazione di questi parametri pu\u00f2 garantire la qualit\u00e0 e l'efficienza produttiva del prodotto e ridurre il tasso di scarti. Queste conoscenze di base sono essenziali per il successo dello stampaggio a iniezione.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-953 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1.jpg\" alt=\"\" class=\"wp-image-41307\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Nello stampaggio a iniezione, per garantire la qualit\u00e0 e l'efficienza del prodotto \u00e8 necessario impostare con precisione temperatura, velocit\u00e0, pressione, posizione e tempo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-954 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"335\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111.jpg\" alt=\"\" class=\"wp-image-41262\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Gli stampi a iniezione di plastica personalizzati devono garantire uno spessore uniforme delle pareti e una corretta linea di divisione dello stampo e utilizzare il rilascio dello stampo. L'ottimizzazione di questi parametri (come la temperatura del materiale, la velocit\u00e0 di iniezione e il tempo di mantenimento) contribuisce a migliorare la qualit\u00e0 del prodotto e a ridurre i cicli di stampaggio.<\/p>\n<p>Inoltre, in <a href=\"https:\/\/zetarmold.com\/it\/\" target=\"_blank\" rel=\"noreferrer noopener\">stampaggio a iniezione di plastica<\/a>Lo stampo a iniezione automatico personalizzato pu\u00f2 essere utilizzato per produrre con precisione parti in plastica della forma desiderata. Le met\u00e0 dello stampo a iniezione personalizzato sono utilizzate per ottimizzare l'uso del materiale di stampaggio, migliorando cos\u00ec la qualit\u00e0 e l'efficienza del prodotto.<\/p>\n<div style=\"background:#f0f4f8;padding:20px;border-radius:8px;margin-top:30px;\">\n<p style=\"margin:0 0 10px;font-size:18px;\"><strong>Need a Quote for Your Injection Molding Project?<\/strong><\/p>\n<p style=\"margin:0 0 10px;\">Get competitive pricing, DFM feedback, and production timeline from ZetarMold\u2019s engineering team.<\/p>\n<p style=\"margin:0;\"><a href=\"https:\/\/zetarmold.com\/it\/contattateci\/\" style=\"background:#2563eb;color:white;padding:12px 24px;border-radius:6px;text-decoration:none;font-weight:bold;\">Request a Free Quote \u2192<\/a> See our <a href=\"https:\/\/zetarmold.com\/it\/guida-completa-allo-stampaggio-a-iniezione\/\">Injection Molding Complete Guide<\/a> for a comprehensive overview.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":41263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Injection Molding Glossary &#038; Basics | ZetarMold","_seopress_titles_desc":"Discover expert insights on injection molding glossary basics from ZetarMold. We provide professional injection molding services with DFM support, fast","_seopress_robots_index":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[42],"tags":[72],"meta_box":{"post-to-quiz_to":[]},"_links":{"self":[{"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/posts\/41251"}],"collection":[{"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/comments?post=41251"}],"version-history":[{"count":0,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/posts\/41251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/media\/41263"}],"wp:attachment":[{"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/media?parent=41251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/categories?post=41251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zetarmold.com\/it\/wp-json\/wp\/v2\/tags?post=41251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}