{"id":41251,"date":"2025-06-20T11:26:52","date_gmt":"2025-06-20T03:26:52","guid":{"rendered":"https:\/\/zetarmold.com\/?p=41251"},"modified":"2026-04-09T08:10:29","modified_gmt":"2026-04-09T00:10:29","slug":"fundamentos-del-glosario-de-moldeo-por-inyeccion","status":"publish","type":"post","link":"https:\/\/zetarmold.com\/es\/fundamentos-del-glosario-de-moldeo-por-inyeccion\/","title":{"rendered":"Glosario y conceptos b\u00e1sicos del moldeo por inyecci\u00f3n"},"content":{"rendered":"<figure class=\"wp-block-embed is-type-rich is-provider-spotify wp-block-embed-spotify wp-embed-aspect-21-9 wp-has-aspect-ratio\">\n<div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Spotify Embed: &lt;a href=\"https:>Molde de inyecci\u00f3n<\/a>ing Glossary &amp; Basics\u201d style=\u201dborder-radius: 12px\u201d width=\u201d100%\u201d height=\u201d152\u2033 frameborder=\u201d0\u2033 allowfullscreen allow=\u201dautoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\u201d loading=\u201dlazy\u201d src=\u201dhttps:\/\/open.spotify.com\/embed\/episode\/1CMeeNSCg0rGXCvSnkrUWu?si=UHbn-LZ1RfeqbnUJMJ2REg&amp;utm_source=oembed\u201d&gt;<\/iframe>\n<\/div>\n<\/figure>\n<p><strong>Introduction: plastic injection molding is a process where plastic particles are heated until they melt and then injected into a mold cavity at high pressure and speed to make a product with the right structure, look, and size.<\/strong><\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-902 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"386\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11.jpg\" alt=\"\" class=\"wp-image-41263\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba11-300x193.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Cuando est\u00e1s moldeando, tienes que pensar en muchas cosas para asegurarte de que tu producto es bueno (c\u00f3mo se ve, qu\u00e9 tan grande es, qu\u00e9 tan fuerte es, y cosas por el estilo) y que puedes hacerlo r\u00e1pido (cu\u00e1nto tiempo se tarda en hacer uno). Este art\u00edculo va a hablar de las palabras y cosas que necesitas saber para hacer moldeo por inyecci\u00f3n.<\/strong><\/p>\n<h2 class=\"wp-block-heading\">Par\u00e1metros de moldeo por inyecci\u00f3n<\/h2>\n<p><strong>Definici\u00f3n: <\/strong>La calidad de moldeo del producto se ve afectada por cinco factores: temperatura, velocidad, presi\u00f3n, posici\u00f3n y tiempo. Los ajustes de estos cinco factores son los par\u00e1metros de moldeo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-903 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"397\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c.jpg\" alt=\"\" class=\"wp-image-41261\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8131\u819c-300x199.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Temperatura <\/h3>\n<h4 class=\"wp-block-heading\">Temperatura de secado<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>La temperatura a la que hay que secar el pl\u00e1stico antes de convertirlo en algo bueno.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Aseg\u00farate de que el pl\u00e1stico est\u00e9 lo m\u00e1s seco posible sin secarse demasiado.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-904 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1.jpg\" alt=\"\" class=\"wp-image-41264\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run2E3T7eNUZLY_Injection_molding_of_medic_8d0af55f-f58a-4e16-a4c5-9824ed949f1d_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> No lo quemes o hagas que se pegue (derrita), hazlo lo m\u00e1s r\u00e1pido que puedas, hazlo lo m\u00e1s fr\u00edo que puedas sin que no funcione, diferentes cosas toman diferentes tiempos y temperaturas, usa lo que dice la gente que lo hizo.<\/p>\n<h4 class=\"wp-block-heading\">Temperatura del material<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> La temperatura que establezca en el tubo de material para asegurarse de que el moldeo va suave.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-905 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0.jpg\" alt=\"\" class=\"wp-image-41266\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rundOI1FsKl6A0_Injection_molding_of_vario_9bca3f9c-0ec7-49e1-9ade-80fb70c64685_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong> Caliente la c\u00e1mara de material de la m\u00e1quina de moldeo con el anillo de calentamiento el\u00e9ctrico para hacer que la materia prima pase de granular a fundida, aseg\u00farese de que el pol\u00edmero se funde bien (pegamento fundido), aseg\u00farese de que el molde se llena y el moldeo se realiza sin problemas.<\/p>\n<p><strong>Principio:<\/strong> No haga que el pl\u00e1stico se descomponga y carbonice, suba desde la secci\u00f3n de alimentaci\u00f3n hasta la boquilla, la temperatura de la boquilla debe ser un poco m\u00e1s baja que la temperatura de la secci\u00f3n frontal del barril para detener el babeo, y la temperatura que necesita depende del material que est\u00e9 utilizando.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-906 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"452\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1.jpg\" alt=\"\" class=\"wp-image-41267\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.rungIvheBqLGlU_plastic_injection_molding__8ab41f06-e40f-4fd1-ae29-1bf4c7863d15_1-300x226.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Temperatura del molde<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>La temperatura de la superficie del molde que toca el producto<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Controle lo r\u00e1pido que se enfr\u00eda el producto en el molde y el aspecto que tiene.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-907 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3.jpeg\" alt=\"\" class=\"wp-image-41073\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/13-3-300x200.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Piense en el tipo de pl\u00e1stico que utiliza, el tama\u00f1o y la forma del producto, y c\u00f3mo se hace el molde. Piensa tambi\u00e9n en c\u00f3mo entra el pl\u00e1stico en el molde.<\/p>\n<h3 class=\"wp-block-heading\">Velocidad<\/h3>\n<h4 class=\"wp-block-heading\">Velocidad de inyecci\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> Velocidad a la que se inyecta el pl\u00e1stico fundido desde la boquilla a la cavidad del molde a una presi\u00f3n determinada.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-908 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12.jpeg\" alt=\"\" class=\"wp-image-41254\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/12-300x169.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong> El aumento de la velocidad de inyecci\u00f3n aumentar\u00e1 la presi\u00f3n de llenado. El aumento de la velocidad de inyecci\u00f3n puede aumentar la longitud de flujo. Esto hace que la calidad del producto sea uniforme. La alta viscosidad y el flujo r\u00e1pido a alta velocidad de inyecci\u00f3n son adecuados para productos de proceso largo. Flujo suave a baja velocidad y tama\u00f1o estable del producto.<\/p>\n<p><strong>Principio:<\/strong> Para evitar el apoyo y el desbordamiento del molde, para evitar quemaduras debidas a una velocidad excesiva y para garantizar la calidad del producto, intente elegir el llenado a alta velocidad para acortar el ciclo de moldeo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-909 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"311\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17.jpeg\" alt=\"\" class=\"wp-image-41255\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/17-300x156.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Velocidad de fusi\u00f3n<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>Qu\u00e9 tan r\u00e1pido va el tornillo cuando est\u00e1 derritiendo el pl\u00e1stico.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Un par\u00e1metro muy importante que afecta a la capacidad de plastificaci\u00f3n, la calidad de plastificaci\u00f3n y el ciclo de moldeo. A mayor velocidad, mayor temperatura de fusi\u00f3n y mayor capacidad de plastificaci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-910 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"300\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7.jpeg\" alt=\"\" class=\"wp-image-41256\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/7-300x150.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Al aumentar la velocidad del tornillo, la calidad de la plastificaci\u00f3n disminuye.<\/p>\n<h4 class=\"wp-block-heading\">Velocidad de repliegue<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>Una vez colocado el tornillo (dosificador), retroceder\u00e1 una cierta distancia a una cierta velocidad. La velocidad de retroceso es la velocidad de retracci\u00f3n.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Reducir el volumen espec\u00edfico de la masa fundida, reducir la presi\u00f3n en la cavidad de la masa fundida y evitar que salga.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-911 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1.jpg\" alt=\"\" class=\"wp-image-41268\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGJgb0J_1O30_Injection_molding_chairs_o_29135d9d-3651-46ed-9936-e7b15f9534b3_0-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>El ajuste debe adaptarse a la velocidad del tornillo y a la contrapresi\u00f3n.<\/p>\n<h4 class=\"wp-block-heading\">Velocidad de apertura y cierre del molde<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>La velocidad de apertura y cierre del molde.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Una velocidad razonable de apertura y cierre del molde es imprescindible para que la m\u00e1quina y la producci\u00f3n funcionen sin problemas.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-912 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"373\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21.jpg\" alt=\"\" class=\"wp-image-41257\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u5f00\u6a21-300x187.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Para que la m\u00e1quina funcione suavemente con menos vibraciones, la velocidad de apertura y cierre del molde debe ajustarse para que el tiempo de apertura y cierre del molde sea lo m\u00e1s corto posible, y la conmutaci\u00f3n de velocidad de apertura y cierre del molde debe ser razonable, siguiendo el principio de lento-r\u00e1pido-lento.<\/p>\n<h4 class=\"wp-block-heading\">Velocidad de avance y retroceso del eyector<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> La velocidad a la que el pasador eyector avanza y se retrae tras la apertura del molde.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Para asegurarse de que la pieza sale del molde sin doblarse, alabearse ni agrietarse.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-913 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"309\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2.jpeg\" alt=\"\" class=\"wp-image-41258\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/2-300x155.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>El extremo delantero debe moverse lentamente para evitar doblar o agrietar la pieza, y el trasero debe moverse r\u00e1pido, pero tiene que ser suave.<\/p>\n<h3 class=\"wp-block-heading\">Presi\u00f3n <\/h3>\n<h4 class=\"wp-block-heading\">Un disparo Presi\u00f3n<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>El tornillo empuja la materia prima desde la tolva hasta el molde.&nbsp;<\/p>\n<p><strong>Funci\u00f3n: <\/strong>Para asegurarse de que el molde est\u00e1 lleno y la pieza sale bien.&nbsp;<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-914 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1.jpg\" alt=\"\" class=\"wp-image-41269\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGXZ4xOOmo-k_plastic_injection_molding__b9c89543-9219-4928-9205-13cc1e200da8_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong>Tiene que estar dentro del l\u00edmite de presi\u00f3n de la m\u00e1quina, la curva de inyecci\u00f3n tiene que estar dentro del rango y la l\u00ednea de presi\u00f3n tiene que ser suave y constante para que no se produzcan destellos o disparos cortos.<\/p>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de inyecci\u00f3n secundaria (presi\u00f3n de mantenimiento)<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> Desde el momento en que la cavidad del molde se llena de pl\u00e1stico hasta que la compuerta se enfr\u00eda y se cierra por completo, se necesita una presi\u00f3n relativamente alta para mantener el tiempo. Esta presi\u00f3n se denomina presi\u00f3n de mantenimiento.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-915 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2.jpg\" alt=\"\" class=\"wp-image-41270\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong> A\u00f1ada m\u00e1s material cerca de la ubicaci\u00f3n de la compuerta y evite que el pl\u00e1stico no endurecido en la cavidad del molde fluya hacia atr\u00e1s bajo la presi\u00f3n restante antes de que la compuerta se enfr\u00ede y se cierre.<\/p>\n<p>Esto evitar\u00e1 que la pieza se encoja, eliminar\u00e1 las marcas de hundimiento, reducir\u00e1 las trampas de aire y evitar\u00e1 que las piezas se peguen al molde o se doblen o rompan debido a una presi\u00f3n de inyecci\u00f3n excesiva.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-916 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0.jpg\" alt=\"\" class=\"wp-image-41271\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> La presi\u00f3n y la velocidad de mantenimiento suelen ajustarse a 50~60% de la presi\u00f3n y la velocidad m\u00e1ximas cuando el pl\u00e1stico llena la cavidad del molde. La duraci\u00f3n del tiempo de mantenimiento est\u00e1 relacionada con la temperatura del material.<\/p>\n<p>La puerta de alta temperatura tiene un tiempo de cierre y un tiempo de retenci\u00f3n m\u00e1s largos. La presi\u00f3n de retenci\u00f3n est\u00e1 relacionada con el \u00e1rea proyectada y el grosor de la pared del producto. Los gruesos y grandes requieren un tiempo m\u00e1s largo. La presi\u00f3n de mantenimiento est\u00e1 relacionada con el tama\u00f1o, la forma y la dimensi\u00f3n de la compuerta.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-917 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2.jpg\" alt=\"\" class=\"wp-image-41272\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi71Zm84u5Iw_Flash_of_various_products__a049b89a-0f2b-45c6-b2b0-11b248967c31_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de la resina (contrapresi\u00f3n)<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> La presi\u00f3n que se crea en la cavidad de fusi\u00f3n durante el proceso de plastificaci\u00f3n del pl\u00e1stico.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Para aumentar la gravedad espec\u00edfica de la masa fundida, garantizar una plastificaci\u00f3n uniforme de la masa fundida, reducir el contenido de gas en la masa fundida y mejorar la calidad de la plastificaci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-918 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1.jpg\" alt=\"\" class=\"wp-image-41273\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runIHncgNE1e50_plastic_product_injection__2f98226e-dd9c-474a-82c4-b8ebdd82ede3_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Al ajustar la presi\u00f3n de la resina, debe tener en cuenta las propiedades del material pl\u00e1stico. Tambi\u00e9n debe tener en cuenta el aspecto y las dimensiones del producto.<\/p>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de apriete<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>El sistema de sujeci\u00f3n es lo que cierra el molde para evitar que se abra al inyectar y envasar el pl\u00e1stico.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-919 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1.jpg\" alt=\"\" class=\"wp-image-41274\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runH2dtixI45_M_Injection_molding_of_vario_2dabdb75-f8f9-4d83-8705-2a5addb7230f_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n: <\/strong>Para que el molde no se abra al inyectar y envasar el pl\u00e1stico, para que la pieza tenga buen aspecto y para que la pieza tenga el tama\u00f1o adecuado.<\/p>\n<p><strong>Principio:<\/strong> El tonelaje de la pinza depende del tama\u00f1o de la pieza y del tama\u00f1o de la m\u00e1quina.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-920 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2.jpg\" alt=\"\" class=\"wp-image-41275\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runk5Wo3vf8AS0_Injection_molding_of_vario_5b7b679b-dce8-44a8-8005-6c359163d791_2-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>En general, cuanto menor sea el tonelaje de la pinza, mejor. El tonelaje de la pinza no debe ser superior a la presi\u00f3n nominal de la m\u00e1quina, pero debe ser lo suficientemente alto como para que la pieza no tenga destellos.<\/p>\n<h4 class=\"wp-block-heading\">Protecci\u00f3n contra el moho Presi\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:&nbsp;<\/strong>Al fabricar moldes, solemos utilizar alta presi\u00f3n y alta velocidad para pasar a baja presi\u00f3n y baja velocidad antes de utilizar alta presi\u00f3n para sujetar el molde. La baja presi\u00f3n antes de la alta presi\u00f3n de sujeci\u00f3n se denomina presi\u00f3n de protecci\u00f3n del molde.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-921 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3.jpg\" alt=\"\" class=\"wp-image-41277\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmuGfiNNZig0_Injection_molding_of_mobil_131781b8-cfa3-4883-8040-cb70c9b02e94_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:&nbsp;<\/strong>Para evitar que el molde sea aplastado por objetos extra\u00f1os en el molde cuando se utiliza alta presi\u00f3n y alta velocidad.<\/p>\n<p><strong>Principio:<\/strong> Antes de ajustar y depurar, primero debemos ajustar el espesor del molde, y el valor de ajuste inicial debe ser lo m\u00e1s bajo posible, y no debe exceder 20% de la fuerza de sujeci\u00f3n. Cuando el molde no se puede corregir, el valor de ajuste debe aumentarse lentamente.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-922 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1.jpg\" alt=\"\" class=\"wp-image-41278\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrpXqUbgNogE_Injection_molding_of_vario_3e937500-1b04-4b4d-a04f-c6cb49352eb5_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Posici\u00f3n <\/h3>\n<h4 class=\"wp-block-heading\">Posici\u00f3n de apertura del molde<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> La posici\u00f3n del molde macho con respecto a la superficie del molde hembra despu\u00e9s de separar los moldes macho y hembra.<\/p>\n<p><strong>Funci\u00f3n:<\/strong>&nbsp;Aseg\u00farese de que puede extraer f\u00e1cilmente el objeto del molde.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-923 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"421\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344.jpg\" alt=\"\" class=\"wp-image-40625\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/08\/Dingtalk_20240807152344-300x211.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio:<\/strong> Vaya tan r\u00e1pido como pueda durante tanto tiempo como pueda. La posici\u00f3n m\u00e1xima de apertura del molde debe basarse en el principio de f\u00e1cil extracci\u00f3n (incluido el robot) y de no da\u00f1ar la superficie del molde hembra al extraerlo. La posici\u00f3n m\u00e1xima de apertura del molde debe basarse en el ciclo de moldeo m\u00e1s corto.<\/p>\n<h4 class=\"wp-block-heading\">Carrera de eyecci\u00f3n y retracci\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> La posici\u00f3n extrema del eyector expulsado y retra\u00eddo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-924 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1.jpg\" alt=\"\" class=\"wp-image-41279\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvpFPwdTSMQU_Injection_molding_of_vario_8785b7ff-dbb4-470e-a8f7-c3e0934ab2a2_0-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong> La carrera del expulsor se utiliza para limitar el movimiento de avance y retroceso del expulsor para garantizar un desmoldeo suave del producto y un restablecimiento preciso del expulsor. En algunos moldes de restablecimiento por muelle, la carrera del expulsor tambi\u00e9n sirve como protecci\u00f3n del l\u00edmite de expulsi\u00f3n.<\/p>\n<p><strong>Principio: <\/strong>La distancia de expulsi\u00f3n debe seguir el principio de peque\u00f1o a grande, y el desmoldeo debe ser suave. En el caso de los moldes de restablecimiento por muelle sin pasadores de l\u00edmite de expulsi\u00f3n, debe garantizarse que el muelle no se aplaste durante la expulsi\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-925 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0.jpg\" alt=\"\" class=\"wp-image-41280\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTRZgJqXMo58_Injection_molding_of_house_28dd5918-4bf4-4cc1-ae15-daee85cef502_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>El pasador eyector no debe estar m\u00e1s alto que la superficie del molde macho cuando est\u00e1 retra\u00eddo. El pasador eyector del molde con corredera debe estar retra\u00eddo para evitar interferencias mutuas.<\/p>\n<h4 class=\"wp-block-heading\">Carrera de medici\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> Una vez iniciada la plastificaci\u00f3n, el husillo empieza a retroceder desde la posici\u00f3n final de inyecci\u00f3n bajo la fuerza de la masa fundida de pl\u00e1stico hasta que alcanza el final de carrera de retroceso durante el proceso de rotaci\u00f3n. Este proceso se denomina carrera de dosificaci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-926 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3.jpg\" alt=\"\" class=\"wp-image-41281\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runrivYKCu_IUI_Injection_molding_of_vario_75f8df7f-4a4e-4276-8a68-e2e4023c4c02_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong>Aseg\u00farese de que tiene suficiente pl\u00e1stico para llenar la cavidad del molde, de modo que obtenga el aspecto y el tama\u00f1o que desea para su producto.<\/p>\n<p><strong>Principio : <\/strong>La carrera de dosificaci\u00f3n debe ajustarse en funci\u00f3n del tama\u00f1o del producto y del tama\u00f1o de la m\u00e1quina. La carrera de dosificaci\u00f3n no debe ser demasiado grande para evitar que la inyecci\u00f3n de pl\u00e1stico sobrante permanezca demasiado tiempo en el tubo de material y provoque carbonizaci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-927 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0.jpg\" alt=\"\" class=\"wp-image-41282\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runTX40mi4wo5M_Various_car_handles_in_var_c0dcf0db-0e37-4a3f-aae0-bcce02938122_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La carrera de dosificaci\u00f3n no puede ser demasiado peque\u00f1a para garantizar un llenado suficiente y evitar da\u00f1os mec\u00e1nicos en el tornillo y la boquilla. Debe haber un tope de 3~5 mm.<\/p>\n<h4 class=\"wp-block-heading\">Carrera de inyecci\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> El tornillo se mueve hacia delante y hacia atr\u00e1s durante el proceso de inyecci\u00f3n.<\/p>\n<p><strong>Funci\u00f3n: <\/strong>El tornillo se mueve r\u00e1pida o lentamente para controlar c\u00f3mo fluye el pl\u00e1stico.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-928 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3.jpg\" alt=\"\" class=\"wp-image-41283\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Principio : <\/strong>La posici\u00f3n de dosificaci\u00f3n viene determinada por la cantidad de llenado del producto final. Normalmente, se a\u00f1aden 3~5 mm de impulso a este valor para determinar el ajuste final. El punto de conmutaci\u00f3n a la segunda velocidad se suele conmutar al canal caliente y a la posici\u00f3n del cabezal.<\/p>\n<p>El punto de conmutaci\u00f3n a la tercera velocidad se establece con 90% del grado de llenado del producto moldeado. El punto de conmutaci\u00f3n de mantenimiento de la presi\u00f3n se establece generalmente en la posici\u00f3n de 90% del grado de llenado del producto acabado.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-929 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3.jpg\" alt=\"\" class=\"wp-image-41284\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runvxtEQA4_gpM_Injection_molding_square_v_956cb755-065b-42ba-bb54-8821c6c18f89_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Retracci\u00f3n Importe<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>Una vez preplastificado (dosificado) en su lugar, el tornillo retrocede una distancia en l\u00ednea recta. Esta acci\u00f3n de retroceso se denomina aflojamiento hacia atr\u00e1s, y la distancia de aflojamiento se denomina cantidad de aflojamiento o cantidad de antiretroceso.<\/p>\n<p><strong>principio:<\/strong> Puede ajustarse en funci\u00f3n de la viscosidad, la densidad relativa y la situaci\u00f3n real de la materia prima pl\u00e1stica. Una cantidad de liberaci\u00f3n mayor har\u00e1 que la masa fundida se mezcle con burbujas, lo que afectar\u00e1 a la calidad del producto.<\/p>\n<p><strong>Funci\u00f3n: <\/strong>La v\u00e1lvula de contrapresi\u00f3n aumenta el volumen de la masa fundida en la c\u00e1mara de dosificaci\u00f3n, reduce la presi\u00f3n interior e impide que la masa fundida salga de la c\u00e1mara de dosificaci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-930 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3.jpg\" alt=\"\" class=\"wp-image-41285\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runYzXTtWdRA4M_Injection_molding_of_vario_b69c43fb-5f8e-4055-b17b-c3ac5152c87f_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>El ajuste de la cantidad de desmoldeo debe adaptarse a la velocidad del husillo y a la contrapresi\u00f3n. Para materias primas con mayor viscosidad (como el PC), se puede ajustar la cantidad de liberaci\u00f3n.<\/p>\n<h4 class=\"wp-block-heading\">Posici\u00f3n residual<\/h4>\n<p><strong>Definici\u00f3n:<\/strong>&nbsp;Cuando termine la inyecci\u00f3n del tornillo, no querr\u00e1 expulsar todo el material fundido de la cabeza del tornillo. Hay que dejar un poco. Al final queda un poco, que es el tamp\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-931 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2.jpg\" alt=\"\" class=\"wp-image-41286\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong>&nbsp;Evite accidentes causados por el golpe de la cabeza del tornillo contra la boquilla. Controle cu\u00e1nto pl\u00e1stico se inyecta cada vez.<\/p>\n<p><strong>principio:<\/strong> No hagas el tamp\u00f3n ni demasiado grande ni demasiado peque\u00f1o. Si es demasiado grande, tendr\u00e1 demasiado material sobrante, lo que provocar\u00e1 p\u00e9rdidas de presi\u00f3n y degradar\u00e1 la materia prima. Si es demasiado peque\u00f1o, no conseguir\u00e1 el efecto amortiguador que busca. La regla general es hacer el tamp\u00f3n de 3 a 5 mm.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-932 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2.jpg\" alt=\"\" class=\"wp-image-41287\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_a_bag_of_orange_and_black_plastic_parts_in_the_styl_94904883-ff0a-4850-8499-3ffec9243cf5_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Tiempo <\/h3>\n<h4 class=\"wp-block-heading\">Ciclo<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>El tiempo transcurrido desde el final de la apertura del molde hasta el final de la apertura del molde despu\u00e9s de la siguiente inyecci\u00f3n se enfr\u00eda.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Aseg\u00farese de que el producto est\u00e1 formado y completamente enfriado y fijado.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-933 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"496\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3.jpg\" alt=\"\" class=\"wp-image-41289\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runi45YzMmm8bc_injection_molding_parts_-_1ff1d81b-5181-4e88-82d4-642b29345945_3-300x248.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Hacer que el ciclo sea lo m\u00e1s corto posible. Acortar el ciclo debe hacerse bajo la premisa de garantizar la calidad del producto.<\/p>\n<h4 class=\"wp-block-heading\">Tiempo de enfriamiento<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> El tiempo que tarda el producto en enfriarse y endurecerse sin estropearse despu\u00e9s de sacarlo del molde.<\/p>\n<p><strong>&nbsp;Funci\u00f3n:<\/strong> Deje que el producto se endurezca. Evite que el producto se ensucie.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-934 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3.jpg\" alt=\"\" class=\"wp-image-41290\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runmRrB60uTAEY_Injection_molding_computer_d4d5f2fe-c510-472d-890c-77e135269b36_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> El tiempo de enfriamiento es una parte importante de la duraci\u00f3n del ciclo y debe ser lo m\u00e1s corto posible sin dejar de garantizar la calidad del producto. (2) El tiempo de enfriamiento depende de la temperatura de la masa fundida, la temperatura del molde, la forma y el grosor del producto.<\/p>\n<h4 class=\"wp-block-heading\">Tiempo de retenci\u00f3n de la prensa<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>La presi\u00f3n que se sigue aplicando despu\u00e9s de la inyecci\u00f3n para evitar el reflujo de pl\u00e1stico despu\u00e9s de la inyecci\u00f3n y la compensaci\u00f3n de la contracci\u00f3n por enfriamiento.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-935 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2.jpg\" alt=\"\" class=\"wp-image-41291\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runonKvqMbIZNU_Small_Mechanical_Parts_GEN_f06f5397-69d5-4c67-825e-955c87376780_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>Funci\u00f3n:<\/strong> Evitar el reflujo de la masa fundida tras la inyecci\u00f3n. Compensaci\u00f3n de la contracci\u00f3n por enfriamiento.<\/p>\n<p><strong>principio:<\/strong> El tiempo de mantenimiento de la prensa depende del grosor del producto. El tiempo de retenci\u00f3n var\u00eda en funci\u00f3n de la temperatura de la masa fundida.<\/p>\n<p>Cuanto mayor sea la temperatura, mayor ser\u00e1 el tiempo necesario, mientras que cuanto menor sea la temperatura, menor ser\u00e1 el tiempo de mantenimiento. Para mejorar la eficacia de la producci\u00f3n, el tiempo de mantenimiento debe ser lo m\u00e1s breve posible, garantizando al mismo tiempo la calidad del producto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-936 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1.jpg\" alt=\"\" class=\"wp-image-41292\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runq0LGsm2lA-w_Detailed_Realism_GENRE_Sti_9e3e82ef-3ea3-4964-a783-9dcc3da5028c_1-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Tiempo de inyecci\u00f3n<\/h4>\n<p><strong>Definici\u00f3n: <\/strong>El tiempo que tarda la masa fundida en llenar toda la cavidad.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> El tiempo de inyecci\u00f3n viene determinado por factores como la presi\u00f3n de inyecci\u00f3n, la velocidad de inyecci\u00f3n y el tama\u00f1o del producto.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-937 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1.jpg\" alt=\"\" class=\"wp-image-41293\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Used6H61-A_Injection_molded_barrels_o_e6e2de41-ce97-4dbf-bd4e-0c7466e9d18f_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> Haga que el tiempo de inyecci\u00f3n sea lo m\u00e1s corto posible, garantizando al mismo tiempo el moldeo del producto. El tiempo de inyecci\u00f3n se ve afectado por factores como la temperatura del material y la temperatura del molde.<\/p>\n<h4 class=\"wp-block-heading\">Tiempo de fusi\u00f3n<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> El tiempo que tarda el tornillo en llegar al final del ca\u00f1\u00f3n despu\u00e9s de detener la inyecci\u00f3n.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Aseg\u00farese de que hay suficiente pl\u00e1stico derretido.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-938 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1.jpg\" alt=\"\" class=\"wp-image-41294\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runUX2Pr0kxt4Y_plastic_injection_molding__2c35dd13-6c52-472a-a410-218b2ae33a5c_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> La velocidad del tornillo y la contrapresi\u00f3n est\u00e1n interrelacionadas. No deje que el pl\u00e1stico fundido permanezca demasiado tiempo en el tornillo, o se descompondr\u00e1 y carbonizar\u00e1 a alta temperatura durante mucho tiempo.<\/p>\n<h4 class=\"wp-block-heading\">Tiempo de secado<\/h4>\n<p><strong>Definici\u00f3n:<\/strong> El tiempo necesario para secar previamente las materias primas mediante equipos de secado.<\/p>\n<p><strong>Funci\u00f3n:<\/strong> Haz que la superficie brille, que sea flexible y resistente, que no se agriete ni burbujee por dentro. Que sea f\u00e1cil y r\u00e1pido de moldear. Que las materias primas no est\u00e9n mojadas ni h\u00famedas.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-939 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2.jpg\" alt=\"\" class=\"wp-image-41295\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_2-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p><strong>principio:<\/strong> El tiempo de secado var\u00eda en funci\u00f3n de las materias primas. Ajuste correctamente el tiempo de secado. Un tiempo demasiado largo reducir\u00e1 la eficacia del secado e incluso har\u00e1 que las materias primas se aglomeren. Un tiempo demasiado corto provocar\u00e1 un efecto de secado deficiente.<\/p>\n<h2 class=\"wp-block-heading\">C\u00f3mo ajustar los par\u00e1metros del proceso de moldeo por inyecci\u00f3n<\/h2>\n<h3 class=\"wp-block-heading\">Temperatura<\/h3>\n<p>Temperature measurement and control are super important in injection molding. It\u2019s pretty easy to make these measurements, but most injection molding machines don\u2019t have enough temperature sampling points or lines.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-940 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1.jpg\" alt=\"\" class=\"wp-image-41296\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runWCpiebvQVDs_Injection_molding_of_comme_fcb76cc2-8e47-473a-82fa-d45dfdc7477e_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La mayor\u00eda de las m\u00e1quinas de moldeo por inyecci\u00f3n utilizan termopares para medir la temperatura. Un termopar son dos cables diferentes conectados por un extremo. Si un extremo est\u00e1 m\u00e1s caliente que el otro, se genera una peque\u00f1a se\u00f1al. Cuanto m\u00e1s caliente est\u00e9, m\u00e1s fuerte ser\u00e1 la se\u00f1al.<\/p>\n<h4 class=\"wp-block-heading\">Temperatura de fusi\u00f3n<\/h4>\n<p>Los termopares tambi\u00e9n se utilizan mucho como sensores en los sistemas de control de temperatura. En el instrumento de control, se ajusta la temperatura deseada y la pantalla del sensor compara la temperatura que detecta con la temperatura ajustada.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-941 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3.jpg\" alt=\"\" class=\"wp-image-41297\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runF0znDyT992E_Injection_molding_of_vario_f4506c61-f6b1-4c90-9efb-8fd9ee770056_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>En el sistema m\u00e1s sencillo, cuando la temperatura alcanza el punto de consigna, la alimentaci\u00f3n se apaga y vuelve a encenderse cuando la temperatura baja. Este sistema se denomina control on-off porque se enciende o se apaga.<\/p>\n<h4 class=\"wp-block-heading\">Control de la temperatura<\/h4>\n<p>La temperatura de fusi\u00f3n es importante y la temperatura del cilindro de inyecci\u00f3n utilizada es s\u00f3lo una gu\u00eda. La temperatura de fusi\u00f3n puede medirse en la boquilla o utilizando el m\u00e9todo de chorro de aire.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-942 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0.jpg\" alt=\"\" class=\"wp-image-41298\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runGFCo_eRXNXg_Injection_molding_of_compu_6386646c-bd2f-4d71-b82f-965ba4c3e033_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>El ajuste de la temperatura del cilindro de inyecci\u00f3n depende de la temperatura de la masa fundida, la velocidad del husillo, la contrapresi\u00f3n, el tama\u00f1o de la inyecci\u00f3n y el ciclo de inyecci\u00f3n.<\/p>\n<p>Si no sabes con qu\u00e9 grado de pl\u00e1stico est\u00e1s trabajando, empieza con el ajuste m\u00e1s bajo. El cilindro de inyecci\u00f3n est\u00e1 dividido en zonas, pero no todas est\u00e1n ajustadas a la misma temperatura.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-943 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0.jpg\" alt=\"\" class=\"wp-image-41299\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runLrirJ0nmGlA_injection_molding_product__9e7a337f-1a1c-4b1c-aa91-4a8da827aaa6_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Si est\u00e1 realizando un trabajo largo o a altas temperaturas, ajuste la temperatura de la primera zona m\u00e1s baja.<\/p>\n<p>Esto evitar\u00e1 que el pl\u00e1stico se derrita y se cortocircuite demasiado pronto. Antes de empezar a moldear, aseg\u00farese de que el aceite hidr\u00e1ulico, el cierre de la tolva, el molde y el cilindro de inyecci\u00f3n est\u00e1n a la temperatura adecuada.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-944 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1.jpg\" alt=\"\" class=\"wp-image-41300\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runSa5u7IoKP1A_Injection_molded_plastic_c_803ed853-f06f-4fe7-8324-b67474c401df_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Presi\u00f3n de inyecci\u00f3n<\/h3>\n<p>Es la presi\u00f3n que hace que el pl\u00e1stico se desplace. Se puede medir con un sensor en la boquilla o en la l\u00ednea hidr\u00e1ulica.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-945 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0.jpg\" alt=\"\" class=\"wp-image-41301\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runxJ2xfa0d-8M_Injection_molding_of_vario_7741867f-e11d-45c4-a261-5d732214af76_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>No tiene un n\u00famero fijo. Cuanto m\u00e1s dif\u00edcil sea llenar el molde, mayor ser\u00e1 la presi\u00f3n de inyecci\u00f3n. La presi\u00f3n de la l\u00ednea de inyecci\u00f3n y la presi\u00f3n de inyecci\u00f3n est\u00e1n directamente relacionadas.<\/p>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de la primera etapa y presi\u00f3n de la segunda etapa<\/h4>\n<p>Durante la fase de llenado del ciclo de inyecci\u00f3n, es posible que necesite una presi\u00f3n de inyecci\u00f3n alta para mantener la velocidad de inyecci\u00f3n donde desea. Una vez que el molde est\u00e9 lleno, ya no necesitar\u00e1 una presi\u00f3n alta.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-946 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"377\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0.jpg\" alt=\"\" class=\"wp-image-41302\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runVvSU0S0DotE_Professional_Product_Photo_75c888f6-4f00-40e0-8152-dca990b8fadd_0-300x189.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Sin embargo, si est\u00e1 inyectando algunos termopl\u00e1sticos semicristalinos (como PA y POM), la estructura se degradar\u00e1 si cambia repentinamente la presi\u00f3n, por lo que a veces no es necesario utilizar la presi\u00f3n de segunda etapa.<\/p>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de apriete<\/h4>\n<p>Para contrarrestar la presi\u00f3n de inyecci\u00f3n, hay que utilizar la presi\u00f3n de apriete. No se limite a seleccionar autom\u00e1ticamente el valor m\u00e1ximo disponible, sino que tenga en cuenta el \u00e1rea proyectada y calcule un valor adecuado.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-947 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0.jpg\" alt=\"\" class=\"wp-image-41303\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runKhO5KvZPHPA_Injection_molded_plastic_b_1c76fa26-bb0e-4bc2-b518-547fbf1c17ac_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>El \u00e1rea proyectada de la pieza moldeada por inyecci\u00f3n es el \u00e1rea m\u00e1xima vista desde la direcci\u00f3n de aplicaci\u00f3n de la fuerza de sujeci\u00f3n.<\/p>\n<p>Para la mayor\u00eda <a href=\"https:\/\/zetarmold.com\/es\/\" data-type=\"link\" data-id=\"https:\/\/zetarmold.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">moldeo por inyecci\u00f3n<\/a> situaciones, es de unas 2 toneladas por pulgada cuadrada, o 31 meganewtons por metro cuadrado. Pero eso es s\u00f3lo un valor bajo y debe ser utilizado como una regla general aproximada, porque,Si la pieza tiene alguna profundidad, debe considerar la pared lateral.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-948 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1.jpg\" alt=\"\" class=\"wp-image-41304\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runPG9Sjj5vzSo_Injection_molding_of_vario_1488c58a-738c-4738-a559-e5dde33336d7_1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h4 class=\"wp-block-heading\">Contrapresi\u00f3n<\/h4>\n<p>Esta es la presi\u00f3n que debe generarse y superarse antes de que el tornillo retroceda. Aunque una contrapresi\u00f3n elevada es buena para la distribuci\u00f3n uniforme de colorantes y la fusi\u00f3n de pl\u00e1sticos, tambi\u00e9n hace que el retorno del tornillo central sea m\u00e1s lento, reduce la longitud de las fibras contenidas en el pl\u00e1stico de relleno y aumenta la tensi\u00f3n de la m\u00e1quina de moldeo por inyecci\u00f3n.<\/p>\n<p>Por tanto, cuanto menor sea la contrapresi\u00f3n, mejor.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-949 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1.jpg\" alt=\"\" class=\"wp-image-41305\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run5Y0u1MddjqA_Two-tone_yellow_and_black__ba2476a9-2855-458a-9df5-40cf32006b95_2-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>En cualquier caso, ninguna de las dos puede superar la presi\u00f3n de moldeo por inyecci\u00f3n de la m\u00e1quina de moldeo por inyecci\u00f3n.<\/p>\n<h4 class=\"wp-block-heading\">Presi\u00f3n de la boquilla<\/h4>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-950 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0.jpg\" alt=\"\" class=\"wp-image-41306\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.run9lE2c01aMZI_Injection_molded_lunch_box_2f9ae61f-7e21-47cd-979c-55526f910627_0-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>La presi\u00f3n de la boquilla es la presi\u00f3n dentro de la boquilla. Es aproximadamente la presi\u00f3n que hace fluir el pl\u00e1stico. No tiene un valor fijo, pero aumenta a medida que el molde es m\u00e1s dif\u00edcil de llenar. La presi\u00f3n de la boquilla, la presi\u00f3n de la l\u00ednea y la presi\u00f3n de inyecci\u00f3n est\u00e1n relacionadas.<\/p>\n<p>La presi\u00f3n de la boquilla es aproximadamente 10% menor que la presi\u00f3n de inyecci\u00f3n. En una m\u00e1quina de moldeo por inyecci\u00f3n de tornillo, la p\u00e9rdida de presi\u00f3n puede ser de aproximadamente 10%. En una m\u00e1quina de moldeo por inyecci\u00f3n de pist\u00f3n, la p\u00e9rdida de presi\u00f3n puede ser 50%.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-951 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3.jpg\" alt=\"\" class=\"wp-image-41308\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runie9wJf3j0oo_injection_molding_product__51272f01-cb92-4a36-886e-6af1adc52e67_3-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<h3 class=\"wp-block-heading\">Velocidad de inyecci\u00f3n<\/h3>\n<p>Se trata de lo r\u00e1pido que se llena el molde cuando el tornillo se utiliza como un \u00e9mbolo. Cuando se disparan piezas de paredes finas, hay que disparar r\u00e1pido para llenar el molde antes de que el pl\u00e1stico se congele y cree una superficie m\u00e1s lisa.<\/p>\n<p>Utilizamos una serie de velocidades de disparo programadas durante el llenado para evitar defectos como la pulverizaci\u00f3n o el aire atrapado. La inyecci\u00f3n puede realizarse bajo un sistema de control de bucle abierto o cerrado.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-952 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"338\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8.jpeg\" alt=\"\" class=\"wp-image-41309\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8.jpeg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/8-300x169.jpeg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>No importa lo r\u00e1pido que inyecte, debe registrar la velocidad en la hoja de registro junto con el tiempo. El tiempo es el tiempo que tarda el molde en alcanzar la presi\u00f3n de inyecci\u00f3n de la primera etapa que usted fij\u00f3, que forma parte del tiempo de avance del tornillo.<\/p>\n<h2 class=\"wp-block-heading\">Resumen<\/h2>\n<p>La calidad y la eficacia del moldeo por inyecci\u00f3n dependen del ajuste \u00f3ptimo de par\u00e1metros como la temperatura, la velocidad, la presi\u00f3n, la posici\u00f3n y el tiempo. El ajuste correcto de estos par\u00e1metros puede garantizar la calidad y la eficiencia de producci\u00f3n del producto y reducir la tasa de desechos. Estos conocimientos b\u00e1sicos son esenciales para llevar a cabo con \u00e9xito el moldeo por inyecci\u00f3n.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-953 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"336\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1.jpg\" alt=\"\" class=\"wp-image-41307\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/zetar6756_httpss.mj_.runh2w0nm-V07s_Injection_molding_of_elect_5d4b99e7-e7a3-480e-8056-93b9dc5d2b4c_1-1-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>En el moldeo por inyecci\u00f3n, para garantizar la calidad y la eficacia del producto es necesario ajustar con precisi\u00f3n la temperatura, la velocidad, la presi\u00f3n, la posici\u00f3n y el tiempo.<\/p>\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-954 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"335\" src=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111.jpg\" alt=\"\" class=\"wp-image-41262\" srcset=\"https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111.jpg 600w, https:\/\/zetarmold.com\/wp-content\/uploads\/2024\/09\/\u8bbe\u8ba111-300x168.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n<\/div>\n<p>Los moldes de inyecci\u00f3n de pl\u00e1stico a medida deben garantizar un grosor de pared uniforme y una l\u00ednea de apertura del molde correcta, y utilizar desmoldeantes. La optimizaci\u00f3n de estos par\u00e1metros (como la temperatura del material, la velocidad de inyecci\u00f3n y el tiempo de mantenimiento) ayuda a mejorar la calidad del producto y a acortar los ciclos de moldeo.<\/p>\n<p>Adem\u00e1s, en <a href=\"https:\/\/zetarmold.com\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">moldeo por inyecci\u00f3n de pl\u00e1stico<\/a>Los moldes de inyecci\u00f3n personalizados autom\u00e1ticos se pueden utilizar para producir con precisi\u00f3n piezas de pl\u00e1stico con la forma deseada. Las mitades de moldes de inyecci\u00f3n personalizados se utilizan para optimizar el uso del material de moldeo, mejorando as\u00ed la calidad y la eficiencia del producto.<\/p>\n<div style=\"background:#f0f4f8;padding:20px;border-radius:8px;margin-top:30px;\">\n<p style=\"margin:0 0 10px;font-size:18px;\"><strong>Need a Quote for Your Injection Molding Project?<\/strong><\/p>\n<p style=\"margin:0 0 10px;\">Get competitive pricing, DFM feedback, and production timeline from ZetarMold\u2019s engineering team.<\/p>\n<p style=\"margin:0;\"><a href=\"https:\/\/zetarmold.com\/es\/contacto\/\" style=\"background:#2563eb;color:white;padding:12px 24px;border-radius:6px;text-decoration:none;font-weight:bold;\">Request a Free Quote \u2192<\/a> See our <a href=\"https:\/\/zetarmold.com\/es\/injection-molding-complete-guide\/\">Injection Molding Complete Guide<\/a> for a comprehensive overview.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":41263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"Injection Molding Glossary &#038; Basics | ZetarMold","_seopress_titles_desc":"Discover expert insights on injection molding glossary basics from ZetarMold. We provide professional injection molding services with DFM support, fast","_seopress_robots_index":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[42],"tags":[72],"meta_box":{"post-to-quiz_to":[]},"_links":{"self":[{"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/posts\/41251"}],"collection":[{"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/comments?post=41251"}],"version-history":[{"count":0,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/posts\/41251\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/media\/41263"}],"wp:attachment":[{"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/media?parent=41251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/categories?post=41251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zetarmold.com\/es\/wp-json\/wp\/v2\/tags?post=41251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}